

{"id":13168,"date":"2021-12-06T16:01:24","date_gmt":"2021-12-06T16:01:24","guid":{"rendered":"https:\/\/magikoravdi.gr\/uncategorized\/%ce%be%cf%85%ce%bb%ce%b9%ce%bd%ce%bf-%cf%83%cf%80%ce%b9%cf%84%ce%b1%ce%ba%ce%b9-%ce%ba%ce%b1%cf%86%ce%b5-zl19c980\/"},"modified":"2024-01-25T18:03:10","modified_gmt":"2024-01-25T16:03:10","slug":"xylino-spitaki-kafe-zl19c980","status":"publish","type":"product","link":"https:\/\/magikoravdi.gr\/en\/vaptisi\/mpomponiera\/ksylina-antikeimena\/xylino-spitaki-kafe-zl19c980\/","title":{"rendered":"WOODEN COFFEE HOUSE ZL19C980"},"content":{"rendered":"<p>\u039e\u03a5\u039b\u0399\u039d\u039f \u03a3\u03a0\u0399\u03a4\u0391\u039a\u0399<\/p>","protected":false},"excerpt":{"rendered":"<p>\u039e\u03a5\u039b\u0399\u039d\u039f \u03a3\u03a0\u0399\u03a4\u0391\u039a\u0399<\/p>","protected":false},"featured_media":13169,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[246,251],"product_tag":[],"class_list":{"0":"post-13168","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-mpomponiera-vaptisi","7":"product_cat-ksylina-antikeimena","8":"tm-has-options","10":"first","11":"onbackorder","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u039e\u03a5\u039b\u0399\u039d\u039f \u03a3\u03a0\u0399\u03a4\u0391\u039a\u0399 \u039a\u0391\u03a6\u0395 ZL19C980 - Magikoravdi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/magikoravdi.gr\/en\/vaptisi\/mpomponiera\/ksylina-antikeimena\/xylino-spitaki-kafe-zl19c980\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u039e\u03a5\u039b\u0399\u039d\u039f \u03a3\u03a0\u0399\u03a4\u0391\u039a\u0399 \u039a\u0391\u03a6\u0395 ZL19C980 - Magikoravdi\" \/>\n<meta property=\"og:description\" content=\"\u039e\u03a5\u039b\u0399\u039d\u039f \u03a3\u03a0\u0399\u03a4\u0391\u039a\u0399\" \/>\n<meta property=\"og:url\" content=\"https:\/\/magikoravdi.gr\/en\/vaptisi\/mpomponiera\/ksylina-antikeimena\/xylino-spitaki-kafe-zl19c980\/\" \/>\n<meta property=\"og:site_name\" content=\"Magikoravdi\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-25T16:03:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/magikoravdi.gr\/wp-content\/uploads\/2021\/12\/ksilino-spitaki-kafe-zl980-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/magikoravdi.gr\\\/en\\\/vaptisi\\\/mpomponiera\\\/ksylina-antikeimena\\\/xylino-spitaki-kafe-zl19c980\\\/\",\"url\":\"https:\\\/\\\/magikoravdi.gr\\\/en\\\/vaptisi\\\/mpomponiera\\\/ksylina-antikeimena\\\/xylino-spitaki-kafe-zl19c980\\\/\",\"name\":\"\u039e\u03a5\u039b\u0399\u039d\u039f \u03a3\u03a0\u0399\u03a4\u0391\u039a\u0399 \u039a\u0391\u03a6\u0395 ZL19C980 - Magikoravdi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/magikoravdi.gr\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/magikoravdi.gr\\\/en\\\/vaptisi\\\/mpomponiera\\\/ksylina-antikeimena\\\/xylino-spitaki-kafe-zl19c980\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/magikoravdi.gr\\\/en\\\/vaptisi\\\/mpomponiera\\\/ksylina-antikeimena\\\/xylino-spitaki-kafe-zl19c980\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/magikoravdi.gr\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/ksilino-spitaki-kafe-zl980-1.jpg\",\"datePublished\":\"2021-12-06T16:01:24+00:00\",\"dateModified\":\"2024-01-25T16:03:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/magikoravdi.gr\\\/en\\\/vaptisi\\\/mpomponiera\\\/ksylina-antikeimena\\\/xylino-spitaki-kafe-zl19c980\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/magikoravdi.gr\\\/en\\\/vaptisi\\\/mpomponiera\\\/ksylina-antikeimena\\\/xylino-spitaki-kafe-zl19c980\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/magikoravdi.gr\\\/en\\\/vaptisi\\\/mpomponiera\\\/ksylina-antikeimena\\\/xylino-spitaki-kafe-zl19c980\\\/#primaryimage\",\"url\":\"https:\\\/\\\/magikoravdi.gr\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/ksilino-spitaki-kafe-zl980-1.jpg\",\"contentUrl\":\"https:\\\/\\\/magikoravdi.gr\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/ksilino-spitaki-kafe-zl980-1.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/magikoravdi.gr\\\/en\\\/vaptisi\\\/mpomponiera\\\/ksylina-antikeimena\\\/xylino-spitaki-kafe-zl19c980\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae\",\"item\":\"https:\\\/\\\/magikoravdi.gr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u039a\u03b1\u03c4\u03ac\u03c3\u03c4\u03b7\u03bc\u03b1\",\"item\":\"https:\\\/\\\/magikoravdi.gr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u039e\u03a5\u039b\u0399\u039d\u039f \u03a3\u03a0\u0399\u03a4\u0391\u039a\u0399 \u039a\u0391\u03a6\u0395 ZL19C980\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/magikoravdi.gr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/magikoravdi.gr\\\/en\\\/\",\"name\":\"Magikoravdi\",\"description\":\"\u0395\u03af\u03b4\u03b7 \u0393\u03ac\u03bc\u03bf\u03c5 &amp; \u0392\u03ac\u03c6\u03c4\u03b9\u03c3\u03b7\u03c2\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/magikoravdi.gr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u039e\u03a5\u039b\u0399\u039d\u039f \u03a3\u03a0\u0399\u03a4\u0391\u039a\u0399 \u039a\u0391\u03a6\u0395 ZL19C980 - Magikoravdi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/magikoravdi.gr\/en\/vaptisi\/mpomponiera\/ksylina-antikeimena\/xylino-spitaki-kafe-zl19c980\/","og_locale":"en_GB","og_type":"article","og_title":"\u039e\u03a5\u039b\u0399\u039d\u039f \u03a3\u03a0\u0399\u03a4\u0391\u039a\u0399 \u039a\u0391\u03a6\u0395 ZL19C980 - Magikoravdi","og_description":"\u039e\u03a5\u039b\u0399\u039d\u039f \u03a3\u03a0\u0399\u03a4\u0391\u039a\u0399","og_url":"https:\/\/magikoravdi.gr\/en\/vaptisi\/mpomponiera\/ksylina-antikeimena\/xylino-spitaki-kafe-zl19c980\/","og_site_name":"Magikoravdi","article_modified_time":"2024-01-25T16:03:10+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/magikoravdi.gr\/wp-content\/uploads\/2021\/12\/ksilino-spitaki-kafe-zl980-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/magikoravdi.gr\/en\/vaptisi\/mpomponiera\/ksylina-antikeimena\/xylino-spitaki-kafe-zl19c980\/","url":"https:\/\/magikoravdi.gr\/en\/vaptisi\/mpomponiera\/ksylina-antikeimena\/xylino-spitaki-kafe-zl19c980\/","name":"\u039e\u03a5\u039b\u0399\u039d\u039f \u03a3\u03a0\u0399\u03a4\u0391\u039a\u0399 \u039a\u0391\u03a6\u0395 ZL19C980 - Magikoravdi","isPartOf":{"@id":"https:\/\/magikoravdi.gr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/magikoravdi.gr\/en\/vaptisi\/mpomponiera\/ksylina-antikeimena\/xylino-spitaki-kafe-zl19c980\/#primaryimage"},"image":{"@id":"https:\/\/magikoravdi.gr\/en\/vaptisi\/mpomponiera\/ksylina-antikeimena\/xylino-spitaki-kafe-zl19c980\/#primaryimage"},"thumbnailUrl":"https:\/\/magikoravdi.gr\/wp-content\/uploads\/2021\/12\/ksilino-spitaki-kafe-zl980-1.jpg","datePublished":"2021-12-06T16:01:24+00:00","dateModified":"2024-01-25T16:03:10+00:00","breadcrumb":{"@id":"https:\/\/magikoravdi.gr\/en\/vaptisi\/mpomponiera\/ksylina-antikeimena\/xylino-spitaki-kafe-zl19c980\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/magikoravdi.gr\/en\/vaptisi\/mpomponiera\/ksylina-antikeimena\/xylino-spitaki-kafe-zl19c980\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/magikoravdi.gr\/en\/vaptisi\/mpomponiera\/ksylina-antikeimena\/xylino-spitaki-kafe-zl19c980\/#primaryimage","url":"https:\/\/magikoravdi.gr\/wp-content\/uploads\/2021\/12\/ksilino-spitaki-kafe-zl980-1.jpg","contentUrl":"https:\/\/magikoravdi.gr\/wp-content\/uploads\/2021\/12\/ksilino-spitaki-kafe-zl980-1.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/magikoravdi.gr\/en\/vaptisi\/mpomponiera\/ksylina-antikeimena\/xylino-spitaki-kafe-zl19c980\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae","item":"https:\/\/magikoravdi.gr\/"},{"@type":"ListItem","position":2,"name":"\u039a\u03b1\u03c4\u03ac\u03c3\u03c4\u03b7\u03bc\u03b1","item":"https:\/\/magikoravdi.gr\/shop\/"},{"@type":"ListItem","position":3,"name":"\u039e\u03a5\u039b\u0399\u039d\u039f \u03a3\u03a0\u0399\u03a4\u0391\u039a\u0399 \u039a\u0391\u03a6\u0395 ZL19C980"}]},{"@type":"WebSite","@id":"https:\/\/magikoravdi.gr\/en\/#website","url":"https:\/\/magikoravdi.gr\/en\/","name":"Magikoravdi","description":"Wedding &amp; Baptism items","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/magikoravdi.gr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/magikoravdi.gr\/en\/wp-json\/wp\/v2\/product\/13168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magikoravdi.gr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/magikoravdi.gr\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/magikoravdi.gr\/en\/wp-json\/wp\/v2\/comments?post=13168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/magikoravdi.gr\/en\/wp-json\/wp\/v2\/media\/13169"}],"wp:attachment":[{"href":"https:\/\/magikoravdi.gr\/en\/wp-json\/wp\/v2\/media?parent=13168"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/magikoravdi.gr\/en\/wp-json\/wp\/v2\/product_brand?post=13168"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/magikoravdi.gr\/en\/wp-json\/wp\/v2\/product_cat?post=13168"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/magikoravdi.gr\/en\/wp-json\/wp\/v2\/product_tag?post=13168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}